{"id":3227,"date":"2016-02-18T18:45:51","date_gmt":"2016-02-18T17:45:51","guid":{"rendered":"http:\/\/www.lelag.fr\/site\/?post_type=tribe_events&#038;p=3227"},"modified":"2016-03-03T11:45:24","modified_gmt":"2016-03-03T10:45:24","slug":"collectif-citoyen-de-lutte-avec-les-goodyear","status":"publish","type":"tribe_events","link":"https:\/\/www.lelag.fr\/site\/agenda\/collectif-citoyen-de-lutte-avec-les-goodyear\/","title":{"rendered":"Collectif citoyen de lutte avec les Goodyear"},"content":{"rendered":"<ul>\n<li>Apr\u00e8s une premi\u00e8re r\u00e9union, le collectif s&rsquo;organise, s&rsquo;\u00e9toff\u00e9, et propose une r\u00e9union publique, avec des films, des \u00e9changes, et des propositions d&rsquo;action<\/li>\n<li>De 19h00 \u00e0 21h00, au LAG<\/li>\n<li>Soir\u00e9e ouverte \u00e0 tous-toutes, et notamment \u00e0 celles et ceux qui entendent dire NON aux attaques en r\u00e8gle contre les travailleurs-travailleuses, et le code du travail<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s une premi\u00e8re r\u00e9union, le collectif s&rsquo;organise, s&rsquo;\u00e9toff\u00e9, et propose une r\u00e9union publique, avec des films, des \u00e9changes, et des propositions d&rsquo;action De 19h00 \u00e0 21h00, au LAG Soir\u00e9e ouverte \u00e0 tous-toutes, et notamment \u00e0 celles et ceux qui entendent &hellip; <a href=\"https:\/\/www.lelag.fr\/site\/agenda\/collectif-citoyen-de-lutte-avec-les-goodyear\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-3227","tribe_events","type-tribe_events","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.lelag.fr\/site\/wp-json\/wp\/v2\/tribe_events\/3227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lelag.fr\/site\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.lelag.fr\/site\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.lelag.fr\/site\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.lelag.fr\/site\/wp-json\/wp\/v2\/tribe_events\/3227\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lelag.fr\/site\/wp-json\/wp\/v2\/media?parent=3227"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lelag.fr\/site\/wp-json\/wp\/v2\/tags?post=3227"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.lelag.fr\/site\/wp-json\/wp\/v2\/tribe_events_cat?post=3227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}